{"id":13289,"date":"2024-01-08T07:59:26","date_gmt":"2024-01-08T00:59:26","guid":{"rendered":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77.png"},"modified":"2024-01-08T07:59:26","modified_gmt":"2024-01-08T00:59:26","slug":"placeholder-png-492","status":"inherit","type":"attachment","link":"https:\/\/bpd.telkomuniversity.ac.id\/en\/placeholder-png-492\/","title":{"rendered":"placeholder.png"},"author":99904,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-13289","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-300x200.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-300x200.png 300w, https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-1024x683.png 1024w, https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-768x512.png 768w, https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-255x170.png 255w, https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1200,"height":800,"file":"2024\/01\/placeholder-77.png","filesize":5443,"sizes":{"medium":{"file":"placeholder-77-300x200.png","width":300,"height":200,"filesize":3887,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-300x200.png"},"large":{"file":"placeholder-77-1024x683.png","width":1024,"height":683,"filesize":18469,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-1024x683.png"},"thumbnail":{"file":"placeholder-77-150x150.png","width":150,"height":150,"filesize":2227,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-150x150.png"},"medium_large":{"file":"placeholder-77-768x512.png","width":768,"height":512,"filesize":12559,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-768x512.png"},"thumb_139x89":{"file":"placeholder-77-139x89.png","width":139,"height":89,"filesize":1749,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-139x89.png"},"thumb_277x337":{"file":"placeholder-77-277x337.png","width":277,"height":337,"filesize":4782,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-277x337.png"},"thumb_50x50":{"file":"placeholder-77-50x50.png","width":50,"height":50,"filesize":760,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-50x50.png"},"thumb_80x80":{"file":"placeholder-77-80x80.png","width":80,"height":80,"filesize":1198,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-80x80.png"},"thumb_263x263":{"file":"placeholder-77-263x263.png","width":263,"height":263,"filesize":4044,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-263x263.png"},"thumb_409x258":{"file":"placeholder-77-409x258.png","width":409,"height":258,"filesize":5653,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-409x258.png"},"thumb_278x178":{"file":"placeholder-77-278x178.png","width":278,"height":178,"filesize":3618,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-278x178.png"},"thumb_554x674":{"file":"placeholder-77-554x674.png","width":554,"height":674,"filesize":11530,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-554x674.png"},"thumb_100x100":{"file":"placeholder-77-100x100.png","width":100,"height":100,"filesize":1478,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-100x100.png"},"thumb_526x526":{"file":"placeholder-77-526x526.png","width":526,"height":526,"filesize":9520,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-526x526.png"},"thumb_818x516":{"file":"placeholder-77-818x516.png","width":818,"height":516,"filesize":13398,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-818x516.png"},"post-thumbnail":{"file":"placeholder-77-255x170.png","width":255,"height":170,"filesize":3277,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-255x170.png"},"thumb_255x255":{"file":"placeholder-77-255x255.png","width":255,"height":255,"filesize":3896,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-255x255.png"},"team-thumb":{"file":"placeholder-77-400x400.png","width":400,"height":400,"filesize":6192,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77-400x400.png"},"full":{"file":"placeholder-77.png","width":1200,"height":800,"mime_type":"image\/png","source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/bpd.telkomuniversity.ac.id\/wp-content\/uploads\/2024\/01\/placeholder-77.png","_links":{"self":[{"href":"https:\/\/bpd.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/media\/13289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bpd.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bpd.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bpd.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/users\/99904"}],"replies":[{"embeddable":true,"href":"https:\/\/bpd.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/comments?post=13289"}]}}